{"id":2360,"date":"2024-05-06T08:22:00","date_gmt":"2024-05-06T08:22:00","guid":{"rendered":"https:\/\/decastroverdelaw.com\/es\/?p=2360"},"modified":"2026-02-01T02:43:19","modified_gmt":"2026-02-01T02:43:19","slug":"extorsion-vs-soborno","status":"publish","type":"post","link":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/","title":{"rendered":"Extorsi\u00f3n vs. Soborno"},"content":{"rendered":"\n<p>La extorsi\u00f3n y el soborno son ambos delitos graves de cuello blanco. Aunque hay similitudes entre estos dos delitos, tambi\u00e9n hay distinciones importantes. En algunos casos, las personas pueden encontrarse con cargos superpuestos de soborno y extorsi\u00f3n.<\/p>\n\n\n\n<p>Si ha sido arrestado o acusado de cualquiera de estos delitos, un abogado de defensa criminal de Las Vegas del Grupo Legal De Castroverde en Criminal e Inmigraci\u00f3n puede explicarle las diferencias entre extorsi\u00f3n y soborno y discutir sus opciones legales.<\/p>\n\n\n\n<p><a href=\"https:\/\/decastroverdelaw.com\/es\/contactenos\/\">Solicite una evaluaci\u00f3n de caso legal<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfSon lo Mismo el Soborno y la Extorsi\u00f3n?<\/strong><\/h2>\n\n\n\n<p>No. El soborno y la extorsi\u00f3n no son lo mismo, aunque estos delitos pueden ser similares. Estos t\u00e9rminos tambi\u00e9n se confunden a veces con los conceptos de chantaje y quid pro quo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es el Soborno?<\/strong><\/h2>\n\n\n\n<p>El soborno consiste en ofrecer, dar, solicitar o recibir dinero o cosas de valor para influir en alguien en un cargo p\u00fablico. Tanto la parte que ofrece el soborno como la que acepta pueden ser culpables de este delito.<\/p>\n\n\n\n<p><strong>Seg\u00fan el C\u00f3digo 18 de los EE. UU. \u00a7 201, hay tres elementos b\u00e1sicos en el soborno:<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ofrecer o prometer dinero o algo de valor a un funcionario p\u00fablico.<\/li>\n\n\n\n<li>Intentar influir en un funcionario para que tome una acci\u00f3n o se abstenga de hacerlo.<\/li>\n\n\n\n<li>Intentar inducir a un funcionario a cometer o permitir un fraude o a hacer o abstenerse de hacer algo que viole su deber p\u00fablico.<\/li>\n<\/ol>\n\n\n\n<p>De manera similar, la ley estatal de Nevada define el soborno como dar, ofrecer o prometer a alguien en un rol de autoridad p\u00fablica cualquier compensaci\u00f3n, gratificaci\u00f3n o recompensa para influir en el desempe\u00f1o de sus deberes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es la Extorsi\u00f3n?<\/strong><\/h2>\n\n\n\n<p>La extorsi\u00f3n es el uso de amenazas, presi\u00f3n o t\u00e1cticas intimidatorias para inducir a otra parte a proporcionar dinero, bienes o servicios. La extorsi\u00f3n generalmente involucra a una parte victimizando a otra. La persona bajo extorsi\u00f3n a menudo no est\u00e1 cometiendo un delito.<\/p>\n\n\n\n<p>Sin embargo, el chantaje es una forma de extorsi\u00f3n donde ambas partes pueden ser culpables. Con el chantaje, la parte extorsionada coopera voluntariamente con el chantajista porque quiere mantener algo oculto. Cuando esto ocurre, la persona chantajeada tambi\u00e9n puede estar violando la ley.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 es Quid Pro Quo?<\/strong><\/h2>\n\n\n\n<p>Es posible que haya escuchado el t\u00e9rmino \u00abquid pro quo\u00bb, que significa \u00abalgo por algo\u00bb. Implica un favor o ventaja a cambio de algo.<\/p>\n\n\n\n<p>El quid pro quo siempre es parte del soborno, pero no todo quid pro quo es soborno. Por ejemplo, cuando realiza una compra en una tienda, intercambia dinero por bienes. T\u00e9cnicamente, esto es quid pro quo, pero no es un delito porque es una transacci\u00f3n hecha de buena fe.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Castigos por Soborno y Extorsi\u00f3n<\/strong><\/h3>\n\n\n\n<p>A nivel federal, el C\u00f3digo 18 de los EE. UU. \u00a7 201 establece que el castigo por soborno es una multa de hasta tres veces la suma involucrada en el delito y hasta 15 a\u00f1os de prisi\u00f3n. Los condenados tambi\u00e9n pueden ser descalificados para ocupar \u00abcualquier cargo de honor, confianza o beneficio bajo los Estados Unidos\u00bb.<\/p>\n\n\n\n<p>Seg\u00fan el C\u00f3digo 18 de los EE. UU. \u00a7 872, el castigo para quienes cometen extorsi\u00f3n puede incluir multas, hasta un a\u00f1o en prisi\u00f3n federal o ambas. Los funcionarios p\u00fablicos culpables de extorsi\u00f3n podr\u00edan enfrentar penas m\u00e1s estrictas, incluyendo hasta tres a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<p>Si el cargo de extorsi\u00f3n involucra comercio interestatal o extranjero, puede ser castigable bajo la Ley Hobbs. Seg\u00fan el Departamento de Justicia de EE. UU., la Ley Hobbs fue promulgada originalmente en la d\u00e9cada de 1940 para combatir el crimen organizado en disputas laborales. Hoy en d\u00eda, se utiliza a menudo para procesar casos de corrupci\u00f3n p\u00fablica. Las condenas bajo la Ley Hobbs pueden llevar una pena de hasta 20 a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<p>A nivel estatal, el castigo por soborno depende de la persona sobornada. El soborno comercial es un delito menor que podr\u00eda resultar en 6 meses de prisi\u00f3n y $1,000 en multas. El soborno a testigos, jueces\/jurados, funcionarios p\u00fablicos o en deportes es un delito grave de Clase C que implica una pena de prisi\u00f3n de entre uno y 10 a\u00f1os y hasta $10,000 en multas.<\/p>\n\n\n\n<p>La extorsi\u00f3n a nivel estatal tambi\u00e9n conlleva una multa de hasta $10,000 y entre uno y 10 a\u00f1os de prisi\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Defensas Contra Cargos de Soborno o Extorsi\u00f3n<\/strong><\/h3>\n\n\n\n<p>Cada caso es diferente, y la mejor defensa en un caso de soborno o extorsi\u00f3n depender\u00e1 de los hechos y circunstancias \u00fanicos involucrados. Sin embargo, las defensas comunes contra el soborno y la extorsi\u00f3n pueden incluir:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Falta de intenci\u00f3n: El soborno y la extorsi\u00f3n son delitos solo si usted tiene la intenci\u00f3n de obtener influencia, servicios, dinero o algo de valor. Podr\u00eda construir una defensa basada en la falta de intenci\u00f3n si puede probar que ese no era el objetivo del intercambio en cuesti\u00f3n.<\/li>\n\n\n\n<li>Falta de valor: Esta defensa argumenta que las cosas intercambiadas no ten\u00edan valor. Por lo tanto, el intercambio no califica como soborno o extorsi\u00f3n.<\/li>\n\n\n\n<li>Falta de involucramiento de un funcionario p\u00fablico: Podr\u00eda demostrar que la parte involucrada en los intercambios no era un funcionario p\u00fablico cuando ocurri\u00f3 el intercambio.<\/li>\n\n\n\n<li>Falta de amenaza: La extorsi\u00f3n ocurre bajo amenaza. Podr\u00eda argumentar que no exist\u00eda tal amenaza.<\/li>\n\n\n\n<li>Falta de pruebas: Los fiscales deben probar que una parte es culpable de soborno o extorsi\u00f3n \u00abm\u00e1s all\u00e1 de toda duda razonable\u00bb. Podr\u00eda demostrar que el fiscal carece de pruebas suficientes de un delito.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 Puede Hacer un Abogado de Defensa Criminal por Usted?<\/strong><\/h3>\n\n\n\n<p>Ser arrestado y acusado de un delito puede ser aterrador. C\u00f3mo procede y qu\u00e9 dice y hace pueden marcar la diferencia en su caso. Con sus finanzas e incluso su libertad en juego, podr\u00eda desear la ayuda de un abogado de defensa criminal experimentado que pueda proteger sus derechos.<\/p>\n\n\n\n<p>El equipo del Grupo Legal De Castroverde en Criminal e Inmigraci\u00f3n puede hacer lo siguiente para defenderlo contra el soborno o la extorsi\u00f3n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Evaluar sus cargos y revisar las pruebas en su contra.<\/li>\n\n\n\n<li>Intentar que sus cargos sean desestimados o reducidos a un delito menor.<\/li>\n\n\n\n<li>Ayudarlo a argumentar por una fianza justa y publicar una fianza.<\/li>\n\n\n\n<li>Investigar su caso y buscar pruebas a su favor.<\/li>\n\n\n\n<li>Tomar declaraciones de testigos.<\/li>\n\n\n\n<li>Representarlo ante un juez o jurado.<\/li>\n\n\n\n<li>Apelar condenas.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Contacte al Grupo Legal De Castroverde en Criminal e Inmigraci\u00f3n para Ayuda en Defensa Criminal<\/strong><\/h4>\n\n\n\n<p>Si bien hay muchas diferencias entre la extorsi\u00f3n y el soborno, ambos son delitos graves con severas penalidades. Si usted o un ser querido enfrenta cargos de soborno o extorsi\u00f3n, un abogado de defensa criminal de Las Vegas del Grupo Legal De Castroverde en Criminal e Inmigraci\u00f3n puede luchar para proteger sus derechos. Llame ahora o cont\u00e1ctenos hoy para una revisi\u00f3n de caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La extorsi\u00f3n y el soborno son ambos delitos graves de cuello blanco. Aunque hay similitudes entre estos dos delitos, tambi\u00e9n hay distinciones importantes. En algunos casos, las personas pueden encontrarse con cargos superpuestos de soborno y extorsi\u00f3n. Si ha sido arrestado o acusado de cualquiera de estos delitos, un abogado de defensa criminal de Las [&hellip;]<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2360","post","type-post","status-publish","format-standard","hentry","category-defensa-penal"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Extorsi\u00f3n vs. Soborno | Los Hermanos De Castroverde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Extorsi\u00f3n vs. Soborno | Los Hermanos De Castroverde\" \/>\n<meta property=\"og:description\" content=\"La extorsi\u00f3n y el soborno son ambos delitos graves de cuello blanco. Aunque hay similitudes entre estos dos delitos, tambi\u00e9n hay distinciones importantes. En algunos casos, las personas pueden encontrarse con cargos superpuestos de soborno y extorsi\u00f3n. Si ha sido arrestado o acusado de cualquiera de estos delitos, un abogado de defensa criminal de Las [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/\" \/>\n<meta property=\"og:site_name\" content=\"Los Hermanos De Castroverde\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-06T08:22:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-01T02:43:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/decastroverdelaw.com\/es\/wp-content\/uploads\/sites\/2\/2026\/02\/de-castroverde-law-og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"De Castroverde Law\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"De Castroverde Law\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/\"},\"author\":{\"name\":\"De Castroverde Law\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#\\\/schema\\\/person\\\/da363c5fa7946f7d35eca4d8069a5f0f\"},\"headline\":\"Extorsi\u00f3n vs. Soborno\",\"datePublished\":\"2024-05-06T08:22:00+00:00\",\"dateModified\":\"2026-02-01T02:43:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/\"},\"wordCount\":1188,\"publisher\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#organization\"},\"articleSection\":[\"Defensa penal\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/\",\"url\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/\",\"name\":\"Extorsi\u00f3n vs. Soborno | Los Hermanos De Castroverde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#website\"},\"datePublished\":\"2024-05-06T08:22:00+00:00\",\"dateModified\":\"2026-02-01T02:43:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/blog\\\/extorsion-vs-soborno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Extorsi\u00f3n vs. Soborno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/\",\"name\":\"Los Hermanos De Castroverde\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#organization\",\"name\":\"Los Hermanos De Castroverde\",\"url\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Logotipo_ESP_EN.jpg\",\"contentUrl\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/02\\\/Logotipo_ESP_EN.jpg\",\"width\":1200,\"height\":1200,\"caption\":\"Los Hermanos De Castroverde\"},\"image\":{\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/decastroverdelaw.com\\\/es\\\/#\\\/schema\\\/person\\\/da363c5fa7946f7d35eca4d8069a5f0f\",\"name\":\"De Castroverde Law\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d608883b83b88e31d0be43a83209dda4089ab4d213769d494e011246b818383?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d608883b83b88e31d0be43a83209dda4089ab4d213769d494e011246b818383?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1d608883b83b88e31d0be43a83209dda4089ab4d213769d494e011246b818383?s=96&d=mm&r=g\",\"caption\":\"De Castroverde Law\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Extorsi\u00f3n vs. Soborno | Los Hermanos De Castroverde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/","og_locale":"es_ES","og_type":"article","og_title":"Extorsi\u00f3n vs. Soborno | Los Hermanos De Castroverde","og_description":"La extorsi\u00f3n y el soborno son ambos delitos graves de cuello blanco. Aunque hay similitudes entre estos dos delitos, tambi\u00e9n hay distinciones importantes. En algunos casos, las personas pueden encontrarse con cargos superpuestos de soborno y extorsi\u00f3n. Si ha sido arrestado o acusado de cualquiera de estos delitos, un abogado de defensa criminal de Las [&hellip;]","og_url":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/","og_site_name":"Los Hermanos De Castroverde","article_published_time":"2024-05-06T08:22:00+00:00","article_modified_time":"2026-02-01T02:43:19+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/decastroverdelaw.com\/es\/wp-content\/uploads\/sites\/2\/2026\/02\/de-castroverde-law-og.jpg","type":"image\/jpeg"}],"author":"De Castroverde Law","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"De Castroverde Law","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/#article","isPartOf":{"@id":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/"},"author":{"name":"De Castroverde Law","@id":"https:\/\/decastroverdelaw.com\/es\/#\/schema\/person\/da363c5fa7946f7d35eca4d8069a5f0f"},"headline":"Extorsi\u00f3n vs. Soborno","datePublished":"2024-05-06T08:22:00+00:00","dateModified":"2026-02-01T02:43:19+00:00","mainEntityOfPage":{"@id":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/"},"wordCount":1188,"publisher":{"@id":"https:\/\/decastroverdelaw.com\/es\/#organization"},"articleSection":["Defensa penal"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/","url":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/","name":"Extorsi\u00f3n vs. Soborno | Los Hermanos De Castroverde","isPartOf":{"@id":"https:\/\/decastroverdelaw.com\/es\/#website"},"datePublished":"2024-05-06T08:22:00+00:00","dateModified":"2026-02-01T02:43:19+00:00","breadcrumb":{"@id":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/decastroverdelaw.com\/es\/blog\/extorsion-vs-soborno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/decastroverdelaw.com\/es\/"},{"@type":"ListItem","position":2,"name":"Extorsi\u00f3n vs. Soborno"}]},{"@type":"WebSite","@id":"https:\/\/decastroverdelaw.com\/es\/#website","url":"https:\/\/decastroverdelaw.com\/es\/","name":"Los Hermanos De Castroverde","description":"","publisher":{"@id":"https:\/\/decastroverdelaw.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/decastroverdelaw.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/decastroverdelaw.com\/es\/#organization","name":"Los Hermanos De Castroverde","url":"https:\/\/decastroverdelaw.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/decastroverdelaw.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/decastroverdelaw.com\/es\/wp-content\/uploads\/sites\/2\/2026\/02\/Logotipo_ESP_EN.jpg","contentUrl":"https:\/\/decastroverdelaw.com\/es\/wp-content\/uploads\/sites\/2\/2026\/02\/Logotipo_ESP_EN.jpg","width":1200,"height":1200,"caption":"Los Hermanos De Castroverde"},"image":{"@id":"https:\/\/decastroverdelaw.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/decastroverdelaw.com\/es\/#\/schema\/person\/da363c5fa7946f7d35eca4d8069a5f0f","name":"De Castroverde Law","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1d608883b83b88e31d0be43a83209dda4089ab4d213769d494e011246b818383?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1d608883b83b88e31d0be43a83209dda4089ab4d213769d494e011246b818383?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1d608883b83b88e31d0be43a83209dda4089ab4d213769d494e011246b818383?s=96&d=mm&r=g","caption":"De Castroverde Law"}}]}},"_links":{"self":[{"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/posts\/2360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/comments?post=2360"}],"version-history":[{"count":1,"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/posts\/2360\/revisions"}],"predecessor-version":[{"id":2361,"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/posts\/2360\/revisions\/2361"}],"wp:attachment":[{"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/media?parent=2360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/categories?post=2360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/decastroverdelaw.com\/es\/wp-json\/wp\/v2\/tags?post=2360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}